{"id":12109,"date":"2024-01-09T10:34:49","date_gmt":"2024-01-09T09:34:49","guid":{"rendered":"https:\/\/equasens.com\/activite\/digipharmacie\/"},"modified":"2024-01-09T10:39:10","modified_gmt":"2024-01-09T09:39:10","slug":"digipharmacie","status":"publish","type":"activite","link":"https:\/\/equasens.com\/en\/activite\/digipharmacie\/","title":{"rendered":"DIGIPHARMACIE"},"content":{"rendered":"<div class=\"container\" data-aos=\"fade-right\"><div class=\"row\"><div class=\"medium-large-full\" >\n<p>DIGIPHARMACIE is a pure player in the field of digitising pharmacy supplier invoices. Offering a SaaS service for pharmacies, the French start-up has a strong technological component in its DNA: the solution enables pharmacies to automatically collect, centralise and archive their supplier invoices, as well as digitising and structuring the flows via artificial intelligence to their accountants&#8217; software. DIGIPHARMACIE&#8217;s turnkey offering is also aimed at the pharmaceutical industry. It meets the requirement to send and receive dematerialised invoices by 1 September 2026.<\/p>\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>DIGIPHARMACIE is a pure player in the field of digitising pharmacy supplier invoices. Offering a SaaS service for pharmacies, the French start-up has a strong technological component in its DNA: the solution enables pharmacies to automatically collect, centralise and archive their supplier invoices, as well as digitising and structuring the flows via artificial intelligence to [&hellip;]<\/p>\n","protected":false},"featured_media":12100,"template":"","class_list":["post-12109","activite","type-activite","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIGIPHARMACIE - Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equasens.com\/en\/activite\/digipharmacie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIGIPHARMACIE - Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9\" \/>\n<meta property=\"og:description\" content=\"DIGIPHARMACIE is a pure player in the field of digitising pharmacy supplier invoices. Offering a SaaS service for pharmacies, the French start-up has a strong technological component in its DNA: the solution enables pharmacies to automatically collect, centralise and archive their supplier invoices, as well as digitising and structuring the flows via artificial intelligence to [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equasens.com\/en\/activite\/digipharmacie\/\" \/>\n<meta property=\"og:site_name\" content=\"Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-09T09:39:10+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/equasens.com\/wp-content\/uploads\/2024\/01\/digi-vecteur-carre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2866\" \/>\n\t<meta property=\"og:image:height\" content=\"3000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/activite\\\/digipharmacie\\\/\",\"url\":\"https:\\\/\\\/equasens.com\\\/en\\\/activite\\\/digipharmacie\\\/\",\"name\":\"DIGIPHARMACIE - Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/activite\\\/digipharmacie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/activite\\\/digipharmacie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/equasens.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/digi-vecteur-carre.png\",\"datePublished\":\"2024-01-09T09:34:49+00:00\",\"dateModified\":\"2024-01-09T09:39:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/activite\\\/digipharmacie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/equasens.com\\\/en\\\/activite\\\/digipharmacie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/activite\\\/digipharmacie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/equasens.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/digi-vecteur-carre.png\",\"contentUrl\":\"https:\\\/\\\/equasens.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/digi-vecteur-carre.png\",\"width\":2866,\"height\":3000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/activite\\\/digipharmacie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/equasens.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIGIPHARMACIE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/equasens.com\\\/en\\\/\",\"name\":\"Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9\",\"description\":\"Plus de technologie pour plus d&#039;humain\",\"publisher\":{\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equasens.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/#organization\",\"name\":\"Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9\",\"url\":\"https:\\\/\\\/equasens.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/equasens.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-logoequasens.png\",\"contentUrl\":\"https:\\\/\\\/equasens.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-logoequasens.png\",\"width\":385,\"height\":226,\"caption\":\"Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/equasens.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIGIPHARMACIE - Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equasens.com\/en\/activite\/digipharmacie\/","og_locale":"en_US","og_type":"article","og_title":"DIGIPHARMACIE - Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9","og_description":"DIGIPHARMACIE is a pure player in the field of digitising pharmacy supplier invoices. Offering a SaaS service for pharmacies, the French start-up has a strong technological component in its DNA: the solution enables pharmacies to automatically collect, centralise and archive their supplier invoices, as well as digitising and structuring the flows via artificial intelligence to [&hellip;]","og_url":"https:\/\/equasens.com\/en\/activite\/digipharmacie\/","og_site_name":"Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9","article_modified_time":"2024-01-09T09:39:10+00:00","og_image":[{"width":2866,"height":3000,"url":"http:\/\/equasens.com\/wp-content\/uploads\/2024\/01\/digi-vecteur-carre.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/equasens.com\/en\/activite\/digipharmacie\/","url":"https:\/\/equasens.com\/en\/activite\/digipharmacie\/","name":"DIGIPHARMACIE - Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9","isPartOf":{"@id":"https:\/\/equasens.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/equasens.com\/en\/activite\/digipharmacie\/#primaryimage"},"image":{"@id":"https:\/\/equasens.com\/en\/activite\/digipharmacie\/#primaryimage"},"thumbnailUrl":"https:\/\/equasens.com\/wp-content\/uploads\/2024\/01\/digi-vecteur-carre.png","datePublished":"2024-01-09T09:34:49+00:00","dateModified":"2024-01-09T09:39:10+00:00","breadcrumb":{"@id":"https:\/\/equasens.com\/en\/activite\/digipharmacie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/equasens.com\/en\/activite\/digipharmacie\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/equasens.com\/en\/activite\/digipharmacie\/#primaryimage","url":"https:\/\/equasens.com\/wp-content\/uploads\/2024\/01\/digi-vecteur-carre.png","contentUrl":"https:\/\/equasens.com\/wp-content\/uploads\/2024\/01\/digi-vecteur-carre.png","width":2866,"height":3000},{"@type":"BreadcrumbList","@id":"https:\/\/equasens.com\/en\/activite\/digipharmacie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/equasens.com\/en\/"},{"@type":"ListItem","position":2,"name":"DIGIPHARMACIE"}]},{"@type":"WebSite","@id":"https:\/\/equasens.com\/en\/#website","url":"https:\/\/equasens.com\/en\/","name":"Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9","description":"Plus de technologie pour plus d&#039;humain","publisher":{"@id":"https:\/\/equasens.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equasens.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/equasens.com\/en\/#organization","name":"Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9","url":"https:\/\/equasens.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/equasens.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/equasens.com\/wp-content\/uploads\/2022\/05\/cropped-logoequasens.png","contentUrl":"https:\/\/equasens.com\/wp-content\/uploads\/2022\/05\/cropped-logoequasens.png","width":385,"height":226,"caption":"Equasens - Acteur structurant de solutions pour les professionnels de sant\u00e9"},"image":{"@id":"https:\/\/equasens.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/equasens.com\/en\/wp-json\/wp\/v2\/activite\/12109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equasens.com\/en\/wp-json\/wp\/v2\/activite"}],"about":[{"href":"https:\/\/equasens.com\/en\/wp-json\/wp\/v2\/types\/activite"}],"version-history":[{"count":3,"href":"https:\/\/equasens.com\/en\/wp-json\/wp\/v2\/activite\/12109\/revisions"}],"predecessor-version":[{"id":12112,"href":"https:\/\/equasens.com\/en\/wp-json\/wp\/v2\/activite\/12109\/revisions\/12112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/equasens.com\/en\/wp-json\/wp\/v2\/media\/12100"}],"wp:attachment":[{"href":"https:\/\/equasens.com\/en\/wp-json\/wp\/v2\/media?parent=12109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}